{"id":609,"count":2,"description":"","link":"https:\/\/wordpress.365scores.com\/news\/tag\/leonard-fournette","name":"Leonard Fournette","slug":"leonard-fournette","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wordpress.365scores.com\/news\/wp-json\/wp\/v2\/tags\/609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.365scores.com\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wordpress.365scores.com\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wordpress.365scores.com\/news\/wp-json\/wp\/v2\/posts?tags=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}